{"id":71914,"date":"2024-01-30T09:27:46","date_gmt":"2024-01-30T09:27:46","guid":{"rendered":"https:\/\/ebarvahaz.hu\/?p=71914"},"modified":"2025-04-25T06:00:46","modified_gmt":"2025-04-25T06:00:46","slug":"misi","status":"publish","type":"post","link":"https:\/\/ebarvahaz.hu\/de\/misi\/","title":{"rendered":"Misi"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<\/p>\n<div class=\"shortcode-gallery dt-format-gallery gallery-col-4 galleryid-71914 dt-gallery-container\" style=\"width: 100%;\"><a href=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi29_0.jpg\" class=\"rollover rollover-zoom dt-pswp-item big-img layzr-bg\" title=\"Misi29_0\"  data-dt-img-description=\"\" data-large_image_width=\"2083\" data-large_image_height = \"1389\"><img fetchpriority=\"high\" decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20600%20600&#39;%2F%3E\" data-src=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi29_0-600x600.jpg\" data-srcset=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi29_0-600x600.jpg 600w, https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi29_0-1200x1200.jpg 1200w\" loading=\"eager\" style=\"--ratio: 600 \/ 600\" sizes=\"(max-width: 600px) 100vw, 600px\" class=\"preload-me lazy-load aspect\" width=\"600\" height=\"600\"  alt=\"Misi29_0\" title=\"Misi29_0\" \/><\/a><a href=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi27_0.jpg\" class=\"rollover rollover-zoom dt-pswp-item layzr-bg\" title=\"Misi27_0\"  data-dt-img-description=\"\" data-large_image_width=\"1977\" data-large_image_height = \"1318\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20300%20300&#39;%2F%3E\" data-src=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi27_0-300x300.jpg\" data-srcset=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi27_0-300x300.jpg 300w, https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi27_0-600x600.jpg 600w\" loading=\"eager\" style=\"--ratio: 300 \/ 300\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"preload-me lazy-load aspect\" width=\"300\" height=\"300\"  alt=\"Misi27_0\" title=\"Misi27_0\" \/><\/a><a href=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi22.jpg\" class=\"rollover rollover-zoom dt-pswp-item layzr-bg\" title=\"Misi22\"  data-dt-img-description=\"\" data-large_image_width=\"1536\" data-large_image_height = \"2048\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20300%20300&#39;%2F%3E\" data-src=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi22-300x300.jpg\" data-srcset=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi22-300x300.jpg 300w, https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi22-600x600.jpg 600w\" loading=\"eager\" style=\"--ratio: 300 \/ 300\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"preload-me lazy-load aspect\" width=\"300\" height=\"300\"  alt=\"Misi22\" title=\"Misi22\" \/><\/a><a href=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi15.jpg\" class=\"rollover rollover-zoom dt-pswp-item layzr-bg\" title=\"Misi15\"  data-dt-img-description=\"\" data-large_image_width=\"2048\" data-large_image_height = \"1536\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20300%20300&#39;%2F%3E\" data-src=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi15-300x300.jpg\" data-srcset=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi15-300x300.jpg 300w, https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi15-600x600.jpg 600w\" loading=\"eager\" style=\"--ratio: 300 \/ 300\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"preload-me lazy-load aspect\" width=\"300\" height=\"300\"  alt=\"Misi15\" title=\"Misi15\" \/><\/a><a href=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi7.jpg\" class=\"rollover rollover-zoom dt-pswp-item layzr-bg\" title=\"Misi7\"  data-dt-img-description=\"\" data-large_image_width=\"1536\" data-large_image_height = \"2048\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20300%20300&#39;%2F%3E\" data-src=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi7-300x300.jpg\" data-srcset=\"https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi7-300x300.jpg 300w, https:\/\/www.ebarvahaz.hu\/wp-content\/uploads\/2024\/01\/Misi7-600x600.jpg 600w\" loading=\"eager\" style=\"--ratio: 300 \/ 300\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"preload-me lazy-load aspect\" width=\"300\" height=\"300\"  alt=\"Misi7\" title=\"Misi7\" \/><\/a><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8220;&#8220;]4 Jahre alter katrierter R\u00fcde<\/p>\n<p><!--more--><\/p>\n<p>Geboren: 01.01.2021<br \/>\nHerkunft: Egyek &#8211; T\u00f6tungsstation<br \/>\nGeschlecht: kastrierter R\u00fcde<\/p>\n<p><strong>Eigenschaften:<\/strong><br \/>\nMenschen, kindern gegen\u00fcber: \u00e4ngstlich<br \/>\nMit Hunde: er kommt mit H\u00fcndinnen gut zurecht, an R\u00fcden kann er gew\u00f6hnt werden<br \/>\nMit Katzen: er l\u00e4sst die Katzen in Frieden<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>UPDATE 13.01.2025: Unser Misike hat sich in der letzten Zeit enorm weiterentwickelt. Mit den Menschen, die er kennengelernt hat, ist er gel\u00f6ster, und auch Fremden gegen\u00fcber \u00f6ffnet er sich immer schneller. Er startet fr\u00f6hlich zu seinen Spazierg\u00e4ngen und genie\u00dft Streicheleinheiten und Zuwendung. Auch H\u00fcndinnen gegen\u00fcber zeigt er Interesse, sucht den Kontakt zu ruhigeren Artgenossen und versucht sogar schon zu spielen. \ud83d\ude42 Jetzt fehlt nur noch ein geduldiger, ruhiger und liebevoller Besitzer, mit dem sich Misike gegenseitig lieben k\u00f6nnten, gemeinsam lange Spazierg\u00e4nge machen oder abends nach einem anstrengenden Tag gl\u00fccklich zusammen auf der Couch kuscheln k\u00f6nnten. Misike ist stubenrein, zerst\u00f6rt seinen Schlafplatz nicht und verh\u00e4lt sich ruhig und entspannt \u2013 ein wirklich idealer Wohnungshund!<\/p>\n<p>&nbsp;<\/p>\n<p>UPDATE 05.04.2024: Misi ist immer noch bei uns im Tierheim, und jeden Tag k\u00fcmmert sich ein anderer Pfleger um ihn, damit er auch f\u00fcr fremde Menschen zug\u00e4nglicher wird.<br \/>\nMisi wird nie der unbeschwerte gl\u00fcckliche Hund sein, der freudig zu seinen Artgenossen rennt, um zu spielen, oder zu Menschen, um gestreichelt zu werden&#8230; Die grausame Behandlung, die er bisher von seinem Leben erfahren hat, hat einen gro\u00dfen Einfluss auf seine kleine Seele hinterlassen.<br \/>\nUm sich weiterzuentwickeln, muss Misi an der Seite seines zuk\u00fcnftigen Besitzers sein. Wir sind an dem Punkt angelangt, an dem eine liebevolle Familie ihm zeigen kann, dass nicht alle Menschen gleich sind.<br \/>\nMisi ben\u00f6tigt mehrere Besuche, um Vertrauen aufzubauen.<\/p>\n<p>&nbsp;<\/p>\n<p>Misi kam am 05.05.2023 in unsere Obhut und wurde noch am selben Tag an einen Trainer vermittelt, weil er vor allem Angst hatte &#x2639; Er konnte nicht im Tierheim mit vielen Hunden bleiben, weil wir Angst hatten, dass er sich noch mehr in sich selbst kehrt &#x2639; Wir kennen seine Vergangenheit nicht, aber es ist sicher, dass er nicht geliebt wurde, sich nicht um ihn gek\u00fcmmert wurde&#8230;ein kaputtes H\u00fcndchen kam zu uns &#x2639;<br \/>\nDie ersten Wochen waren eine Herausforderung mit ihm, da er mit niemandem kooperierte und sich sogar von seinen Hundegef\u00e4hrten v\u00f6llig zur\u00fcckzog. Er war anfangs traumatisiert von gemeinsamen Spazierg\u00e4ngen, jetzt freut er sich ein wenig \u00fcber die Spazierg\u00e4nge, verweigert aber immer noch die Kommunikation. Auch das Streicheln ist f\u00fcr ihn eine Qual und man damit aufh\u00f6rt, atmet er ein wenig auf &#x2639;.<br \/>\nWir wissen nicht, was er in seinem kurzen Leben schon alles durchgemacht hat, aber es wird noch lange dauern, bis wir sagen k\u00f6nnen, dass der kleine Misi zu einem Hund wird, der einen Besitzer sucht. &#x2639;<br \/>\nWie wir geschrieben haben, befindet sich Misi in einer Rehabilitationsma\u00dfnahme mit einem Trainer, die monatlich 45 000 HUF kostet. Bitte unterst\u00fctze die Rehabilitation von Misi, wenn du kannst &lt;3 Danke &#x2764;<\/p>\n<p>&nbsp;<\/p>\n<p>Weitere Bilder: <a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.648068624105530&amp;type=3\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/media\/set\/?set=a.648068624105530&amp;type=3<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Bitte, wenn Du kannst, helfe bei unsere Arbeit mit einer kleinen Spende! Danke!<\/p>\n<p>Kontonummer (Ft): 10700512-68477558-51100005<\/p>\n<p>IBAN: HU48 107005126847755850000005<\/p>\n<p>SWIFT: CIBHHUHB<\/p>\n<p>&nbsp;<\/p>\n<p>Spenden Sie mit PayPal! Danke!<\/p>\n<form action=\"https:\/\/www.paypal.com\/cgi-bin\/webscr\" method=\"post\" target=\"_top\"><input name=\"hosted_button_id\" type=\"hidden\" value=\"W9U5X3QV5WMPL\" \/> <input alt=\"PayPal - The safer, easier way to pay online!\" name=\"submit\" src=\"https:\/\/www.paypalobjects.com\/en_US\/i\/btn\/btn_donateCC_LG.gif\" type=\"image\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.paypalobjects.com\/hu_HU\/i\/scr\/pixel.gif\" alt=\"\" width=\"1\" height=\"1\" border=\"0\" \/><\/p>\n<p>&nbsp;<\/p>\n<\/form>\n<p>\u00a0 Kontakt:<\/p>\n<p><a href=\"http:\/\/www.ebarvahaz.hu\/\">www.ebarvahaz.hu<\/a><\/p>\n<p><a href=\"http:\/\/www.hundewaisenhaus.de\/\">www.hundewaisenhaus.de<\/a><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/ebarvahaz\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/ebarvahaz<\/a><\/p>\n<p>email:\u00a0<a href=\"mailto:info@ebarvahaz.hu\">info@ebarvahaz.hu<\/a><\/p>\n<p>Tel:<\/p>\n<p>+36-20-224-6664<\/p>\n<p>+36-20-314-1003[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>4 Jahre alter katrierter R\u00fcde<\/p>\n","protected":false},"author":12,"featured_media":71944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[91],"tags":[],"class_list":["post-71914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-zuhausegefunden","category-91","description-off"],"_links":{"self":[{"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/posts\/71914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/comments?post=71914"}],"version-history":[{"count":5,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/posts\/71914\/revisions"}],"predecessor-version":[{"id":76123,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/posts\/71914\/revisions\/76123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/media\/71944"}],"wp:attachment":[{"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/media?parent=71914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/categories?post=71914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ebarvahaz.hu\/de\/wp-json\/wp\/v2\/tags?post=71914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}